{"id":6576,"date":"2021-09-13T08:45:08","date_gmt":"2021-09-13T07:45:08","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=6576"},"modified":"2021-09-13T09:59:09","modified_gmt":"2021-09-13T08:59:09","slug":"homelie-du-xxive-dimanche-t-o-b-pere-basile","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/09\/13\/homelie-du-xxive-dimanche-t-o-b-pere-basile\/","title":{"rendered":"HOM\u00c9LIE DU XXIVe DIMANCHE T.O \/ B  (P\u00e8re Basile)"},"content":{"rendered":"\n<p style=\"font-size:18px\">La liturgie de ce 24<sup>e<\/sup> dimanche nous propose des lectures qui nous invitent \u00e0 prendre notre place de disciples, \u00e0 professer notre foi au Christ et \u00e0 la laisser orienter notre vie. Ce qui tombe bien en cette p\u00e9riode des rentr\u00e9es, o\u00f9 il convient de nous pr\u00e9parer \u00e0 mettre davantage en \u0153uvre la foi qui nous anime.<br>Selon l\u2019\u00c9vangile, t\u00e9moin de la bont\u00e9 extraordinaire de J\u00e9sus et de sa puissance qui n\u2019a cess\u00e9 d\u2019impressionner ses contemporains, la foule s\u2019interroge sur son identit\u00e9 v\u00e9ritable : pour certains, il est Jean-Baptiste ressuscit\u00e9&nbsp;; pour d\u2019autres, \u00c9lie&nbsp;; pour d\u2019autres, un des proph\u00e8tes.<br>En s\u2019adressant aux disciples, J\u00e9sus voudrait avoir la r\u00e9ponse de ceux qu\u2019il a envoy\u00e9s en mission. Il attend qu\u2019ils se prononcent avant de les engager dans une deuxi\u00e8me \u00e9tape plus dure&nbsp;: <strong>\u00ab<\/strong>&nbsp;<em>Et vous, que dites-vous&nbsp;? Pour vous, qui suis-je&nbsp;?<\/em>&nbsp;<strong>\u00bb<\/strong> La r\u00e9ponse de Pierre \u00e0 cette question de confiance que pose J\u00e9sus ne se fait pas attendre&nbsp;: <strong>\u00ab<\/strong>&nbsp;<em>Tu es le Christ<\/em>&nbsp;<strong>\u00bb<\/strong>. Par cette r\u00e9ponse, Pierre confesse, sous la conduite de l\u2019Esprit Saint, que J\u00e9sus est le Messie, le roi sorti de la maison de David, le roi annonc\u00e9 et qui doit \u00eatre le v\u00e9ritable Fils de Dieu. Et nous baptis\u00e9s, chr\u00e9tiens d\u2019aujourd\u2019hui, <em>qui est J\u00e9sus pour nous<\/em>&nbsp;<em>?<\/em> <em>Que connaissons-nous vraiment de lui&nbsp;?<\/em> <em>Quelle place lui accordons-nous dans notre vie personnelle&nbsp;?<\/em> Certes, \u00e0 l\u2019exemple et \u00e0 la suite des Ap\u00f4tres, nous confessons d\u00e9j\u00e0 qu\u2019il est le Christ.&nbsp;Mais, comme Pierre, sommes-nous bien conscients de la port\u00e9e d\u2019une telle affirmation&nbsp;? N\u2019oublions pas qu\u2019une foi \u00e9clair\u00e9e et exprim\u00e9e sinc\u00e8rement est fondamentale. <strong>\u00ab<\/strong>&nbsp;Elle engage notre vie chr\u00e9tienne et d\u00e9termine notre attitude envers Dieu. Cette foi met J\u00e9sus au centre de notre vie. Elle nous transformera en profondeur&nbsp;<strong>\u00bb<\/strong>. D\u2019o\u00f9 la n\u00e9cessit\u00e9 de nous instruire sans cesse sur Celui en qui nous croyons, pour saisir davantage la teneur de ses enseignements, consolider notre foi et pouvoir vivre dans son intimit\u00e9, au-del\u00e0 de tout conformisme, sans reculer devant les \u00e9preuves et les difficult\u00e9s de toutes sortes.<br>C\u2019est \u00e0 cette attitude que J\u00e9sus invite les disciples dans la suite de l\u2019\u00c9vangile. Il \u00e9tait bien conscient d\u2019\u00eatre le <em>Messie<\/em>, c\u2019est-\u00e0-dire le Lib\u00e9rateur d\u00e9sign\u00e9 et envoy\u00e9 par Dieu, mais il refusait de donner \u00e0 ce terme une connotation politique, voire militaire. Pour accomplir sa mission, il devait beaucoup souffrir, \u00eatre accus\u00e9, maltrait\u00e9 et mis \u00e0 mort, contrairement aux pens\u00e9es triomphalistes de Pierre et des autres. Pour J\u00e9sus \u2013 et pour nous ses disciples \u2013, le chemin reste celui du serviteur, de ce <em>Serviteur souffrant<\/em> qu\u2019annon\u00e7ait d\u00e9j\u00e0 Isa\u00efe en son temps.<br>Nous voulons suivre le Christ, \u00eatre ses disciples&nbsp;? Eh bien, nous devons nous pr\u00e9parer \u00e0 passer par le m\u00eame chemin que lui. Nous devons renoncer \u00e0 nous-m\u00eames, prendre nos croix et marcher \u00e0 sa suite. En demandant \u00e0 chacun de porter sa croix, J\u00e9sus ne veut pas nous imposer le chemin de l\u2019affliction&nbsp;; il ne veut pas nous inciter \u00e0 aimer la souffrance pour elle-m\u00eame. L\u2019objectif qu\u2019il vise, c\u2019est tout simplement de nous pr\u00e9parer \u00e0 affronter les \u00e9preuves li\u00e9es \u00e0 notre vie de disciples. Il veut nous faire comprendre que le suivre, c\u2019est <em>s\u2019engager dans la voie de l\u2019amour<\/em>, sans se laisser abattre par les \u00e9preuves rencontr\u00e9es en chemin. Rester fid\u00e8le \u00e0 sa foi malgr\u00e9 tout, car <strong>\u00ab<\/strong>&nbsp;<em>je marcherai [\u2026] sur la terre des vivants<\/em>&nbsp;<strong>\u00bb<\/strong>, c\u2019est parfois savoir renoncer \u00e0 ses d\u00e9sirs&nbsp;; c\u2019est savoir aller au-del\u00e0 de ses int\u00e9r\u00eats \u00e9go\u00efstes pour favoriser le royaume de l\u2019amour. Amour <em>agissant<\/em>, qui <strong>\u00ab<\/strong>&nbsp;rend service&nbsp;<strong>\u00bb<\/strong>, qui <strong>\u00ab<\/strong>&nbsp;esp\u00e8re tout&nbsp;<strong>\u00bb<\/strong>, qui <strong>\u00ab<\/strong>&nbsp;endure tout&nbsp;<strong>\u00bb <\/strong>(1 Co 13), dans l\u2019esp\u00e9rance d\u2019obtenir, le moment venu, la vraie joie, le bonheur \u00e9ternel. Tel sera notre boussole tout au long de cette ann\u00e9e, pour le bien de tous et de chacun, et pour la gloire de Dieu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La liturgie de ce 24e dimanche nous propose des lectures qui nous invitent \u00e0 prendre notre place de disciples, \u00e0 professer notre foi au Christ et \u00e0 la laisser orienter notre vie. Ce qui tombe bien en cette p\u00e9riode des rentr\u00e9es, o\u00f9 il convient de nous pr\u00e9parer \u00e0 mettre davantage \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/09\/13\/homelie-du-xxive-dimanche-t-o-b-pere-basile\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-6576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homelie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/04\/Biblr.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1I4","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6576"}],"version-history":[{"count":2,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6576\/revisions"}],"predecessor-version":[{"id":6579,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6576\/revisions\/6579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media\/5360"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}