{"id":6516,"date":"2021-08-23T15:19:46","date_gmt":"2021-08-23T14:19:46","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=6516"},"modified":"2022-11-10T14:32:31","modified_gmt":"2022-11-10T13:32:31","slug":"15-aout-2021","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/08\/23\/15-aout-2021\/","title":{"rendered":"15 ao\u00fbt 2021"},"content":{"rendered":"\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"803\" height=\"1200\" data-attachment-id=\"6518\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/08\/23\/15-aout-2021\/008-3\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/008-scaled-e1629728312729.jpg\" data-orig-size=\"803,1200\" data-comments-opened=\"1\" data-image-title=\"008\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/008-685x1024.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/008-scaled-e1629728312729.jpg\" alt=\"\" class=\"wp-image-6518 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\" style=\"font-size:18px\">Quelle belle c\u00e9l\u00e9bration du 15 ao\u00fbt cette ann\u00e9e encore. Les ann\u00e9es se suivent et se ressemblent car cette messe qu&rsquo;un nombre toujours aussi imposant de fid\u00e8le de tous les villages environnants aiment \u00e0 partager et un beau moment de recueillement et d&rsquo;amiti\u00e9.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-normal-font-size wp-block-paragraph\">&nbsp;Il faut dire aussi que Le P\u00e8re Davy, Thierry notre Diacre, Agn\u00e8s et B\u00e9atrice, Fred contribuent \u00e0 la r\u00e9ussite de cette messe par leurs mots toujours remplis d&#8217;empathie et de bienveillance, leur belle musique et chants si bien interpr\u00e9t\u00e9s,&nbsp;et une sono \u00ab\u00a0au top\u00a0\u00bb. Les hospitaliers qui revenaient de leur traditionnel p\u00e8lerinage \u00e0 Lourdes, ou cette ann\u00e9e il n&rsquo;avait pas emmen\u00e9 de malades, \u00e9taient bien pr\u00e9sents aussi. <\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"803\" data-attachment-id=\"6523\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/002-2\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/002-scaled-e1629728849484.jpg\" data-orig-size=\"1200,803\" data-comments-opened=\"1\" data-image-title=\"002\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/002-1024x685.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/002-scaled-e1629728849484.jpg\" alt=\"\" data-id=\"6523\" data-full-url=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/002-scaled-e1629728849484.jpg\" data-link=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/002-2\/\" class=\"wp-image-6523\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1200\" height=\"803\" data-attachment-id=\"6524\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/007-2\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/007-scaled-e1629728867330.jpg\" data-orig-size=\"1200,803\" data-comments-opened=\"1\" data-image-title=\"007\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/007-1024x685.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/007-scaled-e1629728867330.jpg\" alt=\"\" data-id=\"6524\" data-full-url=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/007-scaled-e1629728867330.jpg\" data-link=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/007-2\/\" class=\"wp-image-6524\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"803\" data-attachment-id=\"6525\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/006\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/006-scaled-e1629728895275.jpg\" data-orig-size=\"1200,803\" data-comments-opened=\"1\" data-image-title=\"006\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/006-1024x685.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/006-scaled-e1629728895275.jpg\" alt=\"\" data-id=\"6525\" data-full-url=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/006-scaled-e1629728895275.jpg\" data-link=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/006\/\" class=\"wp-image-6525\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"900\" data-attachment-id=\"6527\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1100411\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100411-scaled-e1629728935183.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"1\" data-image-title=\"P1100411\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100411-1024x768.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100411-scaled-e1629728935183.jpg\" alt=\"\" data-id=\"6527\" data-full-url=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100411-scaled-e1629728935183.jpg\" data-link=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/p1100411\/\" class=\"wp-image-6527\"\/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"803\" data-attachment-id=\"6526\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/009\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/009-scaled-e1629728918967.jpg\" data-orig-size=\"1200,803\" data-comments-opened=\"1\" data-image-title=\"009\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/009-1024x685.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/009-scaled-e1629728918967.jpg\" alt=\"\" data-id=\"6526\" data-full-url=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/009-scaled-e1629728918967.jpg\" data-link=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/009\/\" class=\"wp-image-6526\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Une \u00e9quipe dynamique se charge d&rsquo;organiser ce rassemblement dans les meilleures conditions possibles.&nbsp;L&rsquo;assembl\u00e9e appr\u00e9cie ce temps fort de l&rsquo;ann\u00e9e liturgique et le fait de prier aussi nombreux r\u00e9unis dans le silence, au pied de cette Madone qui surplombe notre belle&nbsp; r\u00e9gion, apporte \u00e0 tout le monde la force de continuer son chemin. \u00ab\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"6536\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1100435-2\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100435-1-scaled-e1629729525813.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"1\" data-image-title=\"P1100435\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100435-1-1024x768.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2021\/08\/P1100435-1-1024x768.jpg\" alt=\"\" class=\"wp-image-6536\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Quelle belle c\u00e9l\u00e9bration du 15 ao\u00fbt cette ann\u00e9e encore. Les ann\u00e9es se suivent et se ressemblent car cette messe qu&rsquo;un nombre toujours aussi imposant de fid\u00e8le de tous les villages environnants aiment \u00e0 partager et un beau moment de recueillement et d&rsquo;amiti\u00e9. &nbsp;Il faut dire aussi que Le P\u00e8re Davy, \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/08\/23\/15-aout-2021\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-6516","post","type-post","status-publish","format-standard","hentry","category-celebrations"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1H6","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6516"}],"version-history":[{"count":11,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6516\/revisions"}],"predecessor-version":[{"id":6539,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6516\/revisions\/6539"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}