{"id":6069,"date":"2021-02-23T20:55:29","date_gmt":"2021-02-23T19:55:29","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=6069"},"modified":"2021-02-23T22:04:11","modified_gmt":"2021-02-23T21:04:11","slug":"bouquet-de-careme-paroisse-notre-dame-des-sources-en-sanne-dolon","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/02\/23\/bouquet-de-careme-paroisse-notre-dame-des-sources-en-sanne-dolon\/","title":{"rendered":"HOM\u00c9LIE DU 1ER DIMANCHE DE CAR\u00caME B"},"content":{"rendered":"\n<p style=\"font-size:18px;text-align:center\">21 f\u00e9vrier 2021<br> Gen\u00e8se(9,8-15 ) ;1Pierre (3,18-22) ; Marc (1,12-15)<\/p>\n\n\n\n<p style=\"font-size:18px\">\u00ab En ce temps l\u00e0, J\u00e9sus venait d\u2019\u00eatre baptis\u00e9. Aussit\u00f4t l\u2019Esprit le pousse au d\u00e9sert et, dans ce d\u00e9sert, il resta quarante jours, tent\u00e9 par Satan. \u00bb Chaque fois que je lis ce texte de Saint Marc, tous les trois ans, j\u2019ai l\u2019impression d\u2019avoir saut\u00e9 une page<br><\/p>\n\n\n\n<p>En effet, notre m\u00e9moire collective retient un r\u00e9cit des tentations de J\u00e9sus<br>beaucoup plus color\u00e9, \u00e0 l\u2019instar des noces de Cana, de la r\u00e9surrection de Lazare ou de la multiplication des pains.<br>Dans les \u00e9vangiles de Matthieu et de Luc le d\u00e9mon est montr\u00e9, comme on le<br> redoute, rus\u00e9, provocateur, agressif.<br> \u00ab Si tu es le fils de Dieu, ordonne \u00e0 ces pierres de devenir du pain \u00bb<br> \u00ab Si tu te prosternes devant moi, tu auras tous les royaumes de la terre \u00bb<br> \u00ab Si tu es le fils de Dieu jette toi en bas de ce temple \u00bb<br> Pourquoi cette discr\u00e9tion chez Saint Marc ?  <br>Marc a \u00e9t\u00e9 le premier des quatre \u00e9vang\u00e9listes, \u00e0 recueillir des t\u00e9moignages de la vie de J\u00e9sus, \u00e0 les mettre en formes pour t\u00e9moigner et \u00e9duquer les peuples. L\u2019\u00c9vangile de Marc est court, il se lit en moins d\u2019une heure, il va \u00e0 l\u2019essentiel : J\u00e9sus est le fils de Dieu. Sans perdre sa condition divine, il a v\u00e9cu pleinement sa vie d\u2019homme. Il est mort. Il est ressuscit\u00e9. Il est le Sauveur du Monde.  <br>J\u00e9sus est maintenant baptis\u00e9. Les cieux se sont ouverts, signe de la pr\u00e9sence<br>divine dont la voix annonce : \u00ab Tu es mon fils bien-aim\u00e9, en toi j\u2019ai mis tout mon amour \u00bb Il est adulte. Sa mission chez les hommes peut commencer. Mais chez les hommes, il va danger. La libert\u00e9 qui leur est donn\u00e9e se paie d\u2019efforts pour r\u00e9sister aux tentations du monde.<br>L\u2019esprit de Dieu pousse alors J\u00e9sus au d\u00e9sert. Probablement, pour le mettre \u00e0 l\u2019\u00e9preuve, comme on met les jeunes soldats \u00e0 l\u2019\u00e9preuve du feu avant de monter au front.<br>Le d\u00e9sert est, certes, le lieu de la m\u00e9ditation o\u00f9 se sont rendus les proph\u00e8tes Elie et Jean-Baptiste, o\u00f9 se rendront par la suite, Saint Antoine et les p\u00e8res du d\u00e9sert, mais c\u2019est aussi un lieu de solitude, o\u00f9 le silence m\u00eame est agressif, o\u00f9 les organismes, affaiblis par la faim et la soif, sont \u00e0 la merci des tentations du monde.  <br>J\u00e9sus y vivra pendant quarante jours au milieu des b\u00eates sauvages. Il triomphera de toutes les tentations gr\u00e2ce \u00e0 Dieu et \u00e0 \u00ab ses anges qui le servaient. \u00bb Il vivra l\u2019itin\u00e9raire spirituel du peuple de Dieu, quarante ans \u00e0 travers le d\u00e9sert, la mer rouge, les dix plaies d\u2019\u00c9gypte, le veau d\u2019or, etc.<br>Le car\u00eame commence. Le car\u00eame, temps de conversion, de pri\u00e8res et de partage pour vivre pleinement cette f\u00eate du renouveau : la R\u00e9surrection du Christ Pour les cat\u00e9chum\u00e8nes des premiers si\u00e8cles, ce sont quarante jours pour se pr\u00e9parer au bapt\u00eame \u00e0 P\u00e2ques. <br>Pour les p\u00e9nitents, c\u2019est la derni\u00e8re \u00e9tape de conversion avant de r\u00e9int\u00e9grer la communaut\u00e9 dont ils avaient \u00e9t\u00e9 exclus. <br>Que sera notre d\u00e9sert ?<br>Nous avons quarante jours pour regarder dans le r\u00e9troviseur, faire que, dans notre futur, naisse un autre \u00ab nous \u00bb, pour nous convertir, retrouver le chemin que le Christ nous a trac\u00e9.<br>Oh ! ne nous ber\u00e7ons pas d\u2019illusions ! Nous devrons nous contenter de petits pas. Dans la mesure de nos moyens, avec nos charismes, ce sera le temps de modifier notre comportement pour participer \u00e0 la construction du R\u00e8gne de Dieu : \u00ab Les temps sont accomplis \u00bb dit J\u00e9sus.<br>\u00ab N\u2019attendez pas le jugement dernier, dit Albert Camus, il a lieu tous les jours \u00bb   <br>Pour \u00eatre concret, je me risque \u00e0 citer quelques attitudes du quotidien : -Veiller \u00e0 ce que nos relations avec nos semblables soient franches, sans arri\u00e8res pens\u00e9es.<br>-Veiller \u00e0 ce que notre rapport \u00e0 l\u2019argent se limite au n\u00e9cessaire.<br>-\u00catre assidus aux rassemblements dominicaux, l\u00e0, on y rencontre le Christ mais aussi nos fr\u00e8res.<br>-Revoir notre comportement vis-\u00e0-vis de la nature qui est cr\u00e9ation de Dieu ;<br> particuli\u00e8rement pendant cette ann\u00e9e \u00ab Laudato Si \u00bb voulue par le pape Fran\u00e7ois.<br>-Faire un effort sp\u00e9cial pendant cette p\u00e9riode de Pand\u00e9mie, pour nous informer s\u00e9rieusement et vivre cette \u00e9preuve dans l\u2019Esp\u00e9rance.  <br>Le car\u00eame n\u2019est pas seulement un temps de petites privations pour nous pr\u00e9parer \u00e0 P\u00e2ques,<br>c\u2019est aussi le prolongement de l\u2019Alliance que Dieu a faite avec No\u00e9 : quarante jours \u00e0 travers l\u2019eau,<br>renouvel\u00e9e avec Mo\u00efse, 40 ans dans le d\u00e9sert, confirm\u00e9e par J\u00e9sus-Christ,<br>quarante jours au d\u00e9sert, \u00e0 l\u2019\u00e9preuve du Mal.<br>Par excellence le car\u00eame est le renouvellement de notre Alliance avec Dieu :<br>notre BAPT\u00caME.<br>Saint Pierre nous le rappelle dans la deuxi\u00e8me lecture :\u00ab Le bapt\u00eame ne purifie pas de souillures ext\u00e9rieures mais il est l\u2019engagement envers Dieu d\u2019une conscience droite. \u00bb <\/p>\n\n\n\n<p style=\"font-size:18px;text-align:center\"><br><strong>\u00ab Les temps sont accomplis, Convertissez vous et croyez \u00e0 l\u2019\u00c9vangile \u00bb<\/strong><\/p>\n\n\n\n<p><br>Bon car\u00eame.                                                                           Amen<br> <br>Bernard Buisson , diacre<\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>21 f\u00e9vrier 2021 Gen\u00e8se(9,8-15 ) ;1Pierre (3,18-22) ; Marc (1,12-15) \u00ab En ce temps l\u00e0, J\u00e9sus venait d\u2019\u00eatre baptis\u00e9. Aussit\u00f4t l\u2019Esprit le pousse au d\u00e9sert et, dans ce d\u00e9sert, il resta quarante jours, tent\u00e9 par Satan. \u00bb Chaque fois que je lis ce texte de Saint Marc, tous les trois \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2021\/02\/23\/bouquet-de-careme-paroisse-notre-dame-des-sources-en-sanne-dolon\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-6069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homelie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/10\/Hom\u00e9lie-e1602449941510.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1zT","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6069"}],"version-history":[{"count":5,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6069\/revisions"}],"predecessor-version":[{"id":6074,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/6069\/revisions\/6074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media\/5766"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}