{"id":5902,"date":"2020-12-09T07:52:16","date_gmt":"2020-12-09T06:52:16","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=5902"},"modified":"2020-12-09T07:55:38","modified_gmt":"2020-12-09T06:55:38","slug":"le-chemin-et-lesperance","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/12\/09\/le-chemin-et-lesperance\/","title":{"rendered":"Le Chemin et l\u2019Esp\u00e9rance"},"content":{"rendered":"\n<p class=\"has-normal-font-size wp-block-paragraph\">Ce dimanche, les lectures, et l\u2019\u00e9vangile en particulier, sont centr\u00e9es sur le chemin.<br><em>\u00ab\u00a0Pr\u00e9parez les chemins du Seigneur et rendez droit ses sentiers\u2026\u00a0\u00bb <\/em><br>Voil\u00e0, le programme de toute une vie, pour celui qui cultive la dimension m\u00e9taphysique qui est en lui, et qui, ayant soif d\u2019une r\u00e9ponse, se tourne vers l\u2019\u00e9vangile pour emboiter les pas du Seigneur&#8230; <br>Toute sa vie, l\u2019homme cherche un sens \u00e0 sa vie\u00a0; et le sens ne peut \u00eatre donn\u00e9 que par un chemin \u00e0 suivre.   <br>\u00ab\u00a0EGO SUM VIA, VERITAS ET VITA\u00a0\u00bb* est-il grav\u00e9 sur le vitrail du ch\u0153ur  de l\u2019\u00e9glise d\u2019Anjou qui veille sur la table eucharistique.  <br>EGO SUM VIA\u2026 <br>En faisant le pari de suivre les pas du Christ, de s\u2019engager sur son chemin, c\u2019est l\u2019Esp\u00e9rance en un point d\u2019arriv\u00e9e qui nous motive, puis nous habite, et enfin qui nous transforme\u2026<br>-O\u00f9 me conduit ce chemin ? Quelle est ici mon Esp\u00e9rance ?<br>-Ce chemin est-il droit pour moi\u00a0?<br>-Puis-je v\u00e9rifier que je suis sur le bon chemin si chacun de mes pas fortifient mon Esp\u00e9rance et incline mon \u00eatre vers plus d\u2019humanit\u00e9\u00a0?<br>Bonne marche vers No\u00ebl \u00e0 tous\u00a0!<br>Thierry, <strong>d+<\/strong><em>*<\/em><br><em>\u00a0\u00ab\u00a0Je suis le Chemin, la V\u00e9rit\u00e9 et la Vie\u00a0\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche, les lectures, et l\u2019\u00e9vangile en particulier, sont centr\u00e9es sur le chemin.\u00ab\u00a0Pr\u00e9parez les chemins du Seigneur et rendez droit ses sentiers\u2026\u00a0\u00bb Voil\u00e0, le programme de toute une vie, pour celui qui cultive la dimension m\u00e9taphysique qui est en lui, et qui, ayant soif d\u2019une r\u00e9ponse, se tourne vers l\u2019\u00e9vangile \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/12\/09\/le-chemin-et-lesperance\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-5902","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1xc","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5902"}],"version-history":[{"count":3,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5902\/revisions"}],"predecessor-version":[{"id":5905,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5902\/revisions\/5905"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}