{"id":5856,"date":"2020-11-22T10:50:34","date_gmt":"2020-11-22T09:50:34","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=5856"},"modified":"2020-11-22T10:51:17","modified_gmt":"2020-11-22T09:51:17","slug":"homelie-du-22-novembre-2020","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/11\/22\/homelie-du-22-novembre-2020\/","title":{"rendered":"HOM\u00c9LIE du 22 Novembre 2020"},"content":{"rendered":"\n<p style=\"text-align:center\" class=\"has-normal-font-size\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le Christ Roi de l\u2019univers ann\u00e9e A <br>Ez. 34 ,\u00a0 1 Co 15, Mat 25, 31.46 <\/p>\n\n\n\n<p class=\"has-normal-font-size\">La f\u00eate du\u00a0 Christ Roi a \u00e9t\u00e9 instaur\u00e9e en 1925 par le Pape PieXI pour contrecarrer le la\u00efcisme ambiant qui avait conduit au d\u00e9but du XIX \u00e8me si\u00e8cle \u00e0 la suppression des \u00e9tats pontificaux. (Congr\u00e8s de Vienne) L\u2019\u00c9glise a\u00a0 cr\u00e9\u00e9 cette f\u00eate pour annoncer\u00a0 un Christ roi d\u2019une soci\u00e9t\u00e9  humaine \u00e9gale en droits sociaux, en justice, et combattre les  totalitarismes\u00a0 en Europe,\u00a0 qui allaient conduire aux agissements que  l\u2019on sait : la guerre, la Shoah <\/p>\n\n\n\n<p class=\"has-normal-font-size\">F\u00eater le Christ Roi de l\u2019Univers est \u00e0 la foi un pl\u00e9onasme et une incongruit\u00e9. <br>Un pl\u00e9onasme, parce que dans la tradition juive\u00a0: <em>\u00ab\u00a0Le Christ est celui qui a re\u00e7u l\u2019onction de Dieu, et il est\u00a0 le chef du peuple\u00a0\u00bb\u00a0 <\/em>donc le roi ou encore le Berger. <br>Une incongruit\u00e9, parce qu\u2019il n\u2019est pas imaginable qu\u2019on puisse r\u00e9duire  Dieu \u00e0 nos contingences humaines, fussent-elles de le mettre \u00e0 la  premi\u00e8re place. Dieu est le Tout \u2013Autre, l\u2019ind\u00e9finissable.  Une incongruit\u00e9\u00a0 de vouloir donner au fils de Dieu\u00a0 une autorit\u00e9  temporelle,\u00a0 alors que toute sa vie humaine a \u00e9t\u00e9 marqu\u00e9e par son  humilit\u00e9 et son service des plus pauvres. <br>Il est n\u00e9 dans une \u00e9table,\u00a0 il a travaill\u00e9 de ses mains, v\u00e9cu\u00a0 avec les  pauvres, pr\u00each\u00e9 l\u2019amour\u00a0 de ses ennemis, le pardon, le partage, et il  est mort sur une croix comme un brigand.   <br>Bien entendu la liturgie s\u2019appuie sur l\u2019 \u00c9vangile et sur lui seul\u00a0 pour  c\u00e9l\u00e9brer cette f\u00eate. Et si le titre de roi est donn\u00e9 au Christ J\u00e9sus  c\u2019est plus par analogie avec le berger qui donne\u00a0 sa vie pour ses  brebis,\u00a0 que pour marquer une domination. \u00ab <em>Lui qui \u00e9tait de condition divine, s\u2019est fait le serviteur de tous\u00a0\u00bb(<\/em> Ph 2)  La liturgie de cette ann\u00e9e A\u00a0 nous offre le chapitre 25 de l\u2019\u00c9vangile de Matthieu \u00a0qu\u2019on appelle aussi du Jugement dernier.  Matthieu nous parle d\u2019un roi qui, comme le berger s\u00e9pare\u00a0 les brebis des ch\u00e8vres le soir venu au retour des troupeaux.  <br>Mais il n\u2019y a pas d\u2019ambig\u00fcit\u00e9.\u00a0 D\u00e8s le d\u00e9but du chapitre nous sommes fix\u00e9s\u00a0<em>: \u00ab\u00a0Quand le fils de l\u2019homme viendra dans sa gloire,\u00a0 Il si\u00e8gera sur son tr\u00f4ne de gloire, toutes les nations seront r\u00e9unies\u00a0; il s\u00e9parera les hommes les uns des autres\u00a0 comme le berger s\u00e9pare les brebis des boucs.\u00a0\u00bb\u00a0 <\/em>  \u00a0 \u00a0 <br>Le roi de la parabole est donc Dieu, le juge universel qui  interviendra \u00e0 la fin des temps . Car il y aura bien un jugement. Mais y  aura-t-il une condamnation\u00a0? Notre\u00a0 foi en la mis\u00e9ricorde divine nous  fait esp\u00e9rer que non. Car personne n\u2019est tout bon ni tout mauvais et le  feu \u00e9ternel ne peut pas d\u00e9truire\u00a0 ce qui constitue la partie vertueuse  d\u2019une cr\u00e9ature du P\u00e8re.  <br>\u00a0 A la requ\u00eate d\u2019Abraham pour sauver Sodome, <em>\u00ab\u00a0Le seigneur dit\u00a0: Si je trouve dix justes dans la ville de Sodome, je ne la d\u00e9truirai pas \u00e0 cause de ces dix\u00a0\u00bb\u00a0(gen\u00e8se 18-32)<\/em>   <br>Ainsi, ce roi (Dieu) s\u00e9pare les hommes les uns des autres, et place \u00e0 sa droite\u00a0les \u00e9lus:\u00a0<em>\u00ab\u00a0Venez les b\u00e9nis de mon P\u00e8re&#8230;\u00a0\u00bb<\/em>  <br><em>\u00ab\u00a0Car vous m\u2019avez donn\u00e9 \u00e0 manger, donn\u00e9 \u00e0 boire, vous m\u2019avez accueilli, vous m\u2019avez habill\u00e9, vous m\u2019avez visit\u00e9&#8230;.etc\u00a0\u00bb<\/em>  <br>Rien d\u2019extraordinaire, rien qui\u00a0 soit hors de notre port\u00e9e, rien que nous n\u2019accomplissions d\u00e9j\u00e0, \u00e0 notre insu m\u00eame.\u00a0!  <br>A tel point, que comme les justes, \u00e9tonn\u00e9s de la r\u00e9ponse de J\u00e9sus\u00a0 nous pouvons\u00a0 lui poser la\u00a0 question\u00a0: \u00ab\u00a0<em>Quand est ce que nous t\u2019avons vu ?. Quand sommes nous venus jusqu\u2019\u00e0 toi ? \u00bb<\/em>  <br>La r\u00e9ponse surprend :\u00a0<em>\u00ab\u00a0 Chaque fois que vous l\u2019avez fait \u00e0 un de ces petits qui sont mes fr\u00e8res, c\u2019est \u00e0 moi que vous l\u2019avez fait<\/em>\u00a0<br>Elle nous \u00e9tonne aussi,\u00a0 et elle nous chagrine. Comment se fait il que  nous n\u2019ayons\u00a0 jamais vu le Christ dans le visage d\u2019un fr\u00e8re ?&#8230; Notre  \u00e9gocentrisme sans doute ?  Mais nous pouvons nous consoler,\u00a0 parce que l\u2019essentiel a \u00e9t\u00e9 fait. Au  nom de notre humanisme, certes,\u00a0 mais n\u2019est-ce-pas aussi l\u2019humanit\u00e9 du  Christ ? <br>Car ceux qui, sciemment, ne l\u2019ont pas fait, seront jug\u00e9s s\u00e9v\u00e8rement,  maudits et jet\u00e9s dan le feu \u00e9ternel. Certes, le trait est forc\u00e9, car  nous ne pouvons pas imaginer que Dieu puisse condamner,\u00a0 sans r\u00e9mission,  ses propres enfants .  <br>Dans son livre\u00a0\u00ab\u00a0La peste\u00a0\u00bb Camus fait dire par le docteur Rieux au P\u00e8re Paneloux\u00a0: <em>\u00ab\u00a0Je me fais une autre id\u00e9e de l\u2019amour d\u2019un Dieu cr\u00e9ateur d\u2019un monde o\u00f9 meurent des enfants\u00bb<\/em> <br>Eh bien moi, je me fais une autre id\u00e9e\u00a0 du Dieu dont la mis\u00e9ricorde\u00a0 d\u00e9passe toutes nos d\u00e9faillances \u00a0!\u00a0 <em>\u00ab\u00a0L\u00e0 o\u00f9 le p\u00e9ch\u00e9 abonde, la gr\u00e2ce surabonde.\u00a0\u00bb (Romains 5,20)<\/em>   <br>Dimanche prochain, nous\u00a0 entrons dans le temps de l\u2019Avent, la  pr\u00e9paration \u00e0 la naissance de Dieu chez les Hommes, et aussi, le temps\u00a0  o\u00f9 le Christ reviendra dans sa gloire. Le temps\u00a0 du Jugement dernier ou  Dieu(Roi) fera toute chose nouvelle.   <br><em>\u00a0\u00ab\u00a0Venez les b\u00e9nis de mon P\u00e8re, recevez en h\u00e9ritage le Royaume pr\u00e9par\u00e9\u00a0 pour vous depuis le commencement du monde.\u00a0\u00bb<\/em> <br><br>Amen <br><br>Bernard Buisson, Diacre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le Christ Roi de l\u2019univers ann\u00e9e A Ez. 34 ,\u00a0 1 Co 15, Mat 25, 31.46 La f\u00eate du\u00a0 Christ Roi a \u00e9t\u00e9 instaur\u00e9e en 1925 par le Pape PieXI pour contrecarrer le la\u00efcisme ambiant qui avait conduit au d\u00e9but du XIX \u00e8me si\u00e8cle \u00e0 la suppression des \u00e9tats \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/11\/22\/homelie-du-22-novembre-2020\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-5856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homelie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/10\/Hom\u00e9lie-e1602449941510.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1ws","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5856"}],"version-history":[{"count":1,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5856\/revisions"}],"predecessor-version":[{"id":5857,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5856\/revisions\/5857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media\/5766"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}