{"id":5831,"date":"2020-11-03T14:21:00","date_gmt":"2020-11-03T13:21:00","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=5831"},"modified":"2020-11-05T19:12:57","modified_gmt":"2020-11-05T18:12:57","slug":"remerciement","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/11\/03\/remerciement\/","title":{"rendered":"Remerciement"},"content":{"rendered":"\n<p class=\"has-normal-font-size wp-block-paragraph\"><br>Lors de la messe de la rentr\u00e9e pastorale, le dimanche 10 octobre \u00e0 Saint<br>Maurice, c\u2019\u00e9tait aussi une messe d\u2019adieu et d\u2019action gr\u00e2ce pour moi, certains<br>d\u2019entre vous m\u2019ont dit : \u00ab alors, P\u00e8re, vous nous laissez tomber en ce moment de crise sanitaire ? \u00bb Je leur dis gentiment \u00ab j\u2019aimerais bien rester, mais le Seigneur d\u00e9cide autrement et je respecte sa volont\u00e9 \u00bb.<br>Chers confr\u00e8res Pr\u00eatres et diacres, \u00e0 vous les deux \u00e9quipes paroissiales et les Cat\u00e9chistes, \u00e0 vous Chers paroissiens, c\u2019est avec \u00e9motion et beaucoup d\u2019action de gr\u00e2ce que j\u2019exprime ma profonde reconnaissance envers vous, durant ces quatre ann\u00e9es o\u00f9 j\u2019\u00e9tais avec vous. Votre foi active comme votre pri\u00e8re soutenue, votre t\u00e9moignage de vie, m\u2019ont beaucoup aid\u00e9 \u00e0 vivre ma vocation religieuse des missionnaires de la Salette et mon minist\u00e8re de pr\u00eatre.<br>Grand merci pour votre accueil chaleureux, gr\u00e2ce \u00e0 vous je me suis senti utile au service de nos deux paroisses Notre Dame des Sources en Sanne Dolon et Saint Pierre en Pays Roussillonnais. J\u2019\u00e9tais content et heureux d\u2019avoir v\u00e9cu avec vous ces quelques ann\u00e9es. Vous m\u2019avez beaucoup apport\u00e9. Et malgr\u00e9 la crise sanitaire, vous ne voulez pas que je parte en douce, vous m\u2019avez invit\u00e9 \u00e0 la messe de la rentr\u00e9e ; franchement, je ne m\u2019attendais pas \u00e0 \u00e7a. Merci pour le panier garni, pour le don collect\u00e9, cela m\u2019a fait chaud au c\u0153ur.<br>Merci pour tout ce que vous avez fait pour moi. Que Dieu vous le rende au<br>centuple. Vous pouvez compter sur ma pri\u00e8re, et je demande aussi la v\u00f4tre, qui n\u2019a pas de prix, j\u2019en ai besoin, la route sera longue pour moi, pour ma mission.<br>Depuis le 1er septembre, je suis pr\u00eatre vicaire au service de la paroisse Sanctus en Viennois et de la paroisse M\u00e8re Teresa en Viennois ; j\u2019habite toujours \u00e0 Pipet, Vienne, n\u2019h\u00e9sitez pas \u00e0 nous visiter, apr\u00e8s le confinement, Notre Dame de la Salette vous accueille. Petit \u00e0 petit, j\u2019essaie de trouver mes marques.<br>Fr\u00e8res et s\u0153urs, soyons remerci\u00e9s pour les bons moments que nous avons v\u00e9cus ensemble, j\u2019avais bien de la chance de vous rencontrer ; nous restons unis dans la pri\u00e8re et en communion dans le Seigneur<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"5835\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/dsc02235\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/11\/DSC02235-e1604599881543.jpg\" data-orig-size=\"1200,900\" data-comments-opened=\"1\" data-image-title=\"DSC02235\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/11\/DSC02235-1024x768.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/11\/DSC02235-1024x768.jpg\" alt=\"\" class=\"wp-image-5835\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-normal-font-size wp-block-paragraph\">\nP. Joachin RATELOMANANTSOA\n\n<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lors de la messe de la rentr\u00e9e pastorale, le dimanche 10 octobre \u00e0 SaintMaurice, c\u2019\u00e9tait aussi une messe d\u2019adieu et d\u2019action gr\u00e2ce pour moi, certainsd\u2019entre vous m\u2019ont dit : \u00ab alors, P\u00e8re, vous nous laissez tomber en ce moment de crise sanitaire ? \u00bb Je leur dis gentiment \u00ab j\u2019aimerais \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/11\/03\/remerciement\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-5831","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1w3","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5831"}],"version-history":[{"count":3,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5831\/revisions"}],"predecessor-version":[{"id":5836,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5831\/revisions\/5836"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}