{"id":5782,"date":"2020-10-27T09:25:05","date_gmt":"2020-10-27T08:25:05","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=5782"},"modified":"2020-10-27T09:29:34","modified_gmt":"2020-10-27T08:29:34","slug":"30eme-dimanche-du-temps-ordinaire","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/10\/27\/30eme-dimanche-du-temps-ordinaire\/","title":{"rendered":"30\u00e8me dimanche du Temps Ordinaire"},"content":{"rendered":"\n<p style=\"text-align:center\"><strong>\u00ab Le grand, le premier commandement \u00bb<\/strong><\/p>\n\n\n\n<p><strong>Peuple de Dieu,<\/strong><br> Qu\u2019y a-t-il de plus essentiel, de plus d\u00e9sir\u00e9, de plus attendu dans le c\u0153ur de chaque homme que l\u2019amour. L\u2019amour en christianisme a pour nom charit\u00e9 et la charit\u00e9 est le r\u00e9sum\u00e9 de tout l\u2019\u00e9vangile.<br>D\u00e9j\u00e0 \u00e0 travers l\u2019Ancien Testament, Dieu se faisait proche de son peuple par son soutien incontournable manifest\u00e9 \u00e0 son \u00e9gard. La Nouvelle Alliance ne fait qu\u2019incarner cette promesse d\u2019amour \u00e0 l\u2019image du Fils J\u00e9sus, Lui l\u2019arch\u00e9type de la r\u00e9conciliation et de la mis\u00e9ricorde. Par amour pour nous, Dieu s\u2019est r\u00e9v\u00e9l\u00e9 en J\u00e9sus incarn\u00e9 pour nous laisser percevoir son mode d\u2019\u00eatre. Pour J\u00e9sus, la premi\u00e8re place revient \u00e0 l\u2019amour de Dieu mais ce dernier ne va pas \u00e0 sens unique puisqu\u2019il doit se manifester dans l\u2019amour du prochain (Mt 22,36-40).<\/p>\n\n\n\n<p style=\"text-align:center\"><strong>L\u2019amour, paroxysme de la vie chr\u00e9tienne<\/strong><\/p>\n\n\n\n<p>\u00c0 la question du docteur de la loi : \u00ab quel est le plus grand commandement ?\u00bb (Mt 22, 36) J\u00e9sus r\u00e9pond : \u00ab tu aimeras le Seigneur ton Dieu de tout ton c\u0153ur, de toute ton \u00e2me, et de tout ton esprit. Voil\u00e0 le grand, le premier commandement. Et le second lui est semblable : tu aimeras ton prochain comme toi-m\u00eame. De ses deux commandements d\u00e9pend toutes la Loi,<br>ainsi que les Proph\u00e8tes \u00bb (Mt 22, 37-40). Ainsi seul l&rsquo;amour est source et principe de la morale chr\u00e9tienne. La d\u00e9signation ad\u00e9quate du chr\u00e9tien est : celui qui aime. Toutefois il arrive qu&rsquo;on se pose la question de savoir qui entre le Christ et la Charit\u00e9, est la source de la morale chr\u00e9tienne. Faut-il les identifier, ou faut-il les distinguer, comme deux p\u00f4les qui \u00e9quilibrent un univers ? Le tout est de savoir, que ces deux pr\u00e9ceptes sont distincts par leur objet, mais n&rsquo;en font qu&rsquo;un dans leur inspiration. Que ce soit l&rsquo;adoration de Dieu qui exige la fid\u00e9lit\u00e9 \u00e0 sa volont\u00e9 ou la dilection fraternelle qui ordonne la vie au service du prochain, c&rsquo;est un unique amour qui commande la conduite du disciple, l&#8217;emporte sur l\u2019exercice du culte et<br>assure la possession de la vie \u00e9ternelle.<br>Le myst\u00e8re de l\u2019Eucharistie nous rassemble en un seul corps dans le Christ J\u00e9sus. A la lumi\u00e8re de saint Paul, la communion au Corps et au Sang du Christ, ne nous \u00e9loigne pas l\u2019un de l\u2019autre mais au contraire nous rapproche en formant une seule famille dans le Christ. Comme chr\u00e9tien, notre union<br> au Christ passe \u00e9galement par la relation \u00e0 autrui, car c\u2019est pour nous tous qu\u2019Il s\u2019est d\u00e9pouill\u00e9. La relation fraternelle dans notre vie quotidienne semble l\u2019une des caract\u00e9ristiques de l\u2019appartenance au Christ. Celui ou celle qui embrasse la vie du Christ est invit\u00e9 \u00e0 s\u2019ouvrir de plus en plus envers ses<br>semblables en qui l\u2019universalit\u00e9 de l\u2019amour de Dieu est inscrite.<br>J\u00e9sus n\u2019a-t-il pas dans ses messages et dans ses actes faire appara\u00eetre la figure du prochain que Lui a incarn\u00e9 ? La parabole du bon samaritain nous \u00e9claire mieux. Elle nous montre que le prochain n\u2019est pas uniquement les personnes de notre clan mais celui \u00e0 qui je dois mon aide dans n\u2019importe quelle circonstance et \u00e0 travers un lieu donn\u00e9. C\u2019est en apportant une<br>r\u00e9ponse directe aux besoins des autres et en s\u2019aidant mutuellement que cet exercice se concr\u00e9tise.<br>Aimer le Christ ne se vit pas uniquement de fa\u00e7on verticale mais cela doit se traduire dans nos actes quotidiens, en d\u00e9veloppant notre capacit\u00e9 d\u2019atteindre l\u2019autre dans sa souffrance et l\u2019aider \u00e0 se reconstruire. Pour y arriver, cela requiert de chacun une attention particuli\u00e8re \u00e0 l\u2019\u00e9gard de nos fr\u00e8res et s\u0153urs.<br>D\u2019autre part, en restant \u00e0 la suite de Jean nous pouvons nous demander comment l\u2019amour est-il possible ? Puisque Dieu est invisible. S\u2019il est vrai qu\u2019Il \u00e9chappe \u00e0 nos yeux, par quels moyens pouvons-nous manifester notre amour et notre attachement \u00e0 Lui. La premi\u00e8re lettre de Jean semble trouver une bonne formule pour nous \u00e9clairer sur ce sujet en nous<br>disant : \u00ab En effet celui qui n\u2019aime pas son fr\u00e8re, qu\u2019il voit, est incapable d\u2019aimer Dieu, qu\u2019il ne voit pas \u00bb (1Jn 4,20). Pour le disciple bien aim\u00e9, l\u2019amour divin est intimement li\u00e9 \u00e0 l\u2019amour du prochain. Autrement dit, c\u2019est dans l\u2019autre que je d\u00e9couvre le vrai visage de Dieu, car il continue encore de se r\u00e9v\u00e9ler \u00e0 nous. L\u2019Amour de Dieu ne resplendira pas si chacun de nous se contente de son petit projet personnel jusqu&rsquo;\u00e0 exclure l\u2019autre. Nous ne pouvons pas aimer Dieu et oublier les soucis de nos fr\u00e8res et s\u0153urs qui peinent \u00e0 se reconstruire. L\u2019amour vrai se traduit dans nos actes de tous les jours, il se manifeste dans l\u2019entraide, le partage et la communion fraternelle.<br>\u00c0 la suite du Christ le disciple est appel\u00e9 \u00e0 vivre dans l&rsquo;amour, et de Dieu et du prochain, dans le sens o\u00f9 cet amour s&rsquo;est incarn\u00e9 et est le fondement de la relation de l&rsquo;homme avec Dieu et de l&rsquo;homme avec l&rsquo;autre, ainsi sans lui l&rsquo;homme ne peut vivre. C&rsquo;est en cela que Saint Paul dit dans son hymne \u00e0 l&rsquo;amour ce qui suit : \u00ab j&rsquo;aurais beau parler toutes les langues des hommes et des anges, si je n&rsquo;ai pas la charit\u00e9, s&rsquo;il me manque l&rsquo;amour, je ne suis qu&rsquo;un cuivre qui r\u00e9sonne, une cymbale retentissante. (\u2026) Ce qui demeure aujourd&rsquo;hui, c&rsquo;est la foi, l&rsquo;esp\u00e9rance et la charit\u00e9 ; mais la plus grande des trois, c&rsquo;est la charit\u00e9 \u00bb (1Co 13, 1-13).<\/p>\n\n\n\n<p>P\u00e8re Thomas MESIDOR<\/p>\n\n\n\n<p><br> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Le grand, le premier commandement \u00bb Peuple de Dieu, Qu\u2019y a-t-il de plus essentiel, de plus d\u00e9sir\u00e9, de plus attendu dans le c\u0153ur de chaque homme que l\u2019amour. L\u2019amour en christianisme a pour nom charit\u00e9 et la charit\u00e9 est le r\u00e9sum\u00e9 de tout l\u2019\u00e9vangile.D\u00e9j\u00e0 \u00e0 travers l\u2019Ancien Testament, Dieu \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/10\/27\/30eme-dimanche-du-temps-ordinaire\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-5782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homelie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2020\/10\/Hom\u00e9lie-e1602449941510.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1vg","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5782"}],"version-history":[{"count":2,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5782\/revisions"}],"predecessor-version":[{"id":5784,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5782\/revisions\/5784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media\/5766"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}