{"id":5582,"date":"2020-09-09T20:10:51","date_gmt":"2020-09-09T19:10:51","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=5582"},"modified":"2020-09-09T20:39:17","modified_gmt":"2020-09-09T19:39:17","slug":"rentree-de-laumonerie-2","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/09\/09\/rentree-de-laumonerie-2\/","title":{"rendered":"Rentr\u00e9e de l&rsquo;aum\u00f4nerie"},"content":{"rendered":"\n<p> Ce dimanche 06 septembre 2020 s&rsquo;est tenu en l&rsquo;\u00e9glise d&rsquo;Anjou la messe de  rentr\u00e9e de l&rsquo;aum\u00f4nerie. Messe a laquelle les jeunes ont pris part en  faisant les lectures. <br>S&rsquo;en est suivi un repas convivial en plein air \u00e0 la maison paroissiale  d&rsquo;Anjou avec les animateurs, les jeunes et leur parents. L&rsquo;occasion de  retrouver les jeunes de l&rsquo;ann\u00e9e pass\u00e9e qui continuent leur parcours et  de faire connaissance avec les nouveaux arrivants et leurs parents.  <br>En d\u00e9but d&rsquo;apr\u00e8s-midi, J\u00e9r\u00f4me, le responsable de l&rsquo;aum\u00f4nerie, a   pr\u00e9sent\u00e9 aux jeunes et \u00e0 leurs parents l&rsquo;aum\u00f4nerie et le programme de   l&rsquo;ann\u00e9e :Les animateurs sont Gilles, Christine et J\u00e9r\u00f4me.Le p\u00e8re Davy  est l&rsquo;accompagnateur spirituel de l&rsquo;aum\u00f4nerie.  <br>Le groupe des sixi\u00e8mes sera pris en charge, comme les ann\u00e9es  pr\u00e9c\u00e9dentes, par Gilles et le p\u00e8re Davy.Le groupe des 5\u00b0 \u00e0 la 3\u00b0 sera  pris en charge par Christine.Le groupe des 2nde \u00e0 la terminale sera pris  en charge par J\u00e9r\u00f4me. En plus des rencontres de chaque groupe, J\u00e9r\u00f4me a \u00e9galement pr\u00e9sent\u00e9 les  temps forts qui attendent les jeunes au cour de cette ann\u00e9e : la  confirmation pour 5 d&rsquo;entre eux, la messe de No\u00ebl, un apr\u00e8s-midi  d\u00e9couverte des moyens de prier, la journ\u00e9e Connect&rsquo;, la marche des  Rameaux et un p\u00e8lerinage. <br>Le p\u00e8re Davy a achev\u00e9 la rencontre par un temps de spiritualit\u00e9, un Notre P\u00e8re et un Je Vous Salue Marie.\u00a0\u00bb    <\/p>\n\n\n\n<p>  <\/p>\n\n\n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce dimanche 06 septembre 2020 s&rsquo;est tenu en l&rsquo;\u00e9glise d&rsquo;Anjou la messe de rentr\u00e9e de l&rsquo;aum\u00f4nerie. Messe a laquelle les jeunes ont pris part en faisant les lectures. S&rsquo;en est suivi un repas convivial en plein air \u00e0 la maison paroissiale d&rsquo;Anjou avec les animateurs, les jeunes et leur parents. \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2020\/09\/09\/rentree-de-laumonerie-2\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-5582","post","type-post","status-publish","format-standard","hentry","category-aumonerie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-1s2","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5582"}],"version-history":[{"count":1,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5582\/revisions"}],"predecessor-version":[{"id":5583,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/5582\/revisions\/5583"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}