{"id":10021,"date":"2025-04-15T12:53:52","date_gmt":"2025-04-15T11:53:52","guid":{"rendered":"https:\/\/paroisse-notredame-sannedolon.fr\/?p=10021"},"modified":"2025-11-13T21:21:11","modified_gmt":"2025-11-13T20:21:11","slug":"marche-des-rameaux-3","status":"publish","type":"post","link":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2025\/04\/15\/marche-des-rameaux-3\/","title":{"rendered":"Marche des Rameaux"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:38% auto\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"769\" data-attachment-id=\"10023\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1010091\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010091-scaled-e1744718364640.jpg\" data-orig-size=\"1200,901\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;6.3&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-G80&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744450640&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Marche des Rameaux 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010091-1024x769.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010091-1024x769.jpg\" alt=\"\" class=\"wp-image-10023 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><br>Ce samedi 12 avril 2025, \u00e0 Salaise-sur-Sanne, une trentaine d\u2019adultes des paroisses St Pierre et Notre Dame s\u2019\u00e9taient donn\u00e9s rendez-vous pour une marche autour de Salaise-sur-Sanne avec les jeunes de la cat\u00e9ch\u00e8se, de l\u2019aum\u00f4nerie, des \u00e9coles. Ce qui formait un groupe d\u2019une soixantaine de personnes toute g\u00e9n\u00e9ration confondue qui s\u2019est mis en marche derri\u00e8re la croix.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\" style=\"grid-template-columns:auto 45%\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><br>En chemin, nous nous sommes \u00e9merveill\u00e9s de la nature, nous avons admirer la cr\u00e9ation avec le cantique des cr\u00e9atures de Saint Fran\u00e7ois d\u2019Assise.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1024\" height=\"769\" data-attachment-id=\"10026\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1010095\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010095-scaled-e1744718457372.jpg\" data-orig-size=\"1200,901\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-G80&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744452231&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Marche des Rameaux 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010095-1024x769.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010095-1024x769.jpg\" alt=\"\" class=\"wp-image-10026 size-full\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-medium-font-size\"><br>Puis nous nous sommes rendus au prieur\u00e9 datant du XI \u00e8me si\u00e8cle. Gr\u00e2ce \u00e0 Mr Valette, nous avons pu visiter le ch\u0153ur, la crypte de l\u2019ancienne \u00e9glise, le jardin m\u00e9dicinal, class\u00e9s au titre des Monuments historiques\u2026<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"260\" height=\"194\" data-attachment-id=\"10855\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/jardin-prieure-2\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1.jpeg\" data-orig-size=\"260,194\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"jardin prieur\u00e9\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1.jpeg\" data-id=\"10855\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1.jpeg\" alt=\"\" class=\"wp-image-10855\" srcset=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1.jpeg 260w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1-150x112.jpeg 150w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/jardin-prieure-1-201x150.jpeg 201w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" data-attachment-id=\"10849\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/crypte-prieure\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure.jpg\" data-orig-size=\"275,183\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"crypte prieur\u00e9\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure.jpg\" data-id=\"10849\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure.jpg\" alt=\"\" class=\"wp-image-10849\" srcset=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure.jpg 275w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure-150x100.jpg 150w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/crypte-prieure-225x150.jpg 225w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"630\" data-attachment-id=\"10040\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/prieure-de-salaise-sur-sanne_15107920-2\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1.jpg\" data-orig-size=\"945,630\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;X-Pro2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1653929654&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;128&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.000625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"prieure-de-salaise-sur-sanne_15107920\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1.jpg\" data-id=\"10040\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1.jpg\" alt=\"\" class=\"wp-image-10040\" srcset=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1.jpg 945w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1-300x200.jpg 300w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1-150x100.jpg 150w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/prieure-de-salaise-sur-sanne_15107920-1-225x150.jpg 225w\" sizes=\"(max-width: 945px) 100vw, 945px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-attachment-id=\"10029\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1010102\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010102-scaled-e1744718582312.jpg\" data-orig-size=\"1200,901\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-G80&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744456535&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Marche des Rameaux 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010102-1024x769.jpg\" data-id=\"10029\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010102-1024x769.jpg\" alt=\"\" class=\"wp-image-10029\"\/><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><br>Ensuite nous avons repris le chemin, pass\u00e9 sur le pont aux moines, le plus vieux pont de la commune, qui permettait aux moines du prieur\u00e9 de franchir la Sanne \u00e0 pied. L\u00e0, nous avons pri\u00e9 avec les saints patrons des \u00e9coles, des villages des 2 paroisses.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"183\" data-attachment-id=\"10854\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/pont\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont.jpeg\" data-orig-size=\"275,183\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"pont salaise sur sanne\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont.jpeg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont.jpeg\" alt=\"\" class=\"wp-image-10854 size-full\" srcset=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont.jpeg 275w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont-150x100.jpeg 150w, https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/11\/pont-225x150.jpeg 225w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:46% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" data-attachment-id=\"10027\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1010097\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010097-scaled-e1744718506980.jpg\" data-orig-size=\"1200,901\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-G80&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744452960&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Marche des Rameaux 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010097-1024x769.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010097-1024x769.jpg\" alt=\"\" class=\"wp-image-10027 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size\"><br>Notre marche a permis de d\u00e9couvrir ou red\u00e9couvrir les croix des missions (1889), \u00e9rig\u00e9e en souvenir d\u2019une mission, c\u2019est-\u00e0-dire une retraite spirituelle. Elles ont connu un essor apr\u00e8s la r\u00e9volution car l\u2019\u00e9glise souhaitait restaurer la pratique religieuse et raviver la foi des fid\u00e8les. A cette occasion, nous avons, par le chant, acclamez J\u00e9sus, en ce jour des Rameaux&nbsp;: \u00ab&nbsp;Voici celui qui vient au nom du Seigneur. Acclamons notre roi, hosannah&nbsp;!&nbsp;\u00bb<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Avant de prendre le repas pique-nique, nous avons pri\u00e9 avec l\u2019Ang\u00e9lus.L\u2019apr\u00e8s-midi s\u2019est d\u00e9roul\u00e9e avec des ateliers int\u00e9rieurs et ext\u00e9rieurs, la croix s\u2019est fleurie magnifiquement. Avec l\u2019\u00e9veil \u00e0 la foi, c\u2019est tous ensemble que nous avons particip\u00e9 \u00e0 la messe des Rameaux dans l\u2019\u00e9glise de Salaise o\u00f9 d\u2019autres membres de la communaut\u00e9 nous ont rejoints.<\/p>\n\n\n\n<p class=\"has-medium-font-size\">Tout le monde est reparti, enchant\u00e9 de cette journ\u00e9e ensoleill\u00e9e.Nous souhaitons \u00e0 tous de bonnes f\u00eates pascales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"499\" data-attachment-id=\"10030\" data-permalink=\"https:\/\/paroisse-notredame-sannedolon.fr\/p1010104\/\" data-orig-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010104-scaled-e1744718608996.jpg\" data-orig-size=\"1200,585\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DMC-G80&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744456537&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;15&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Marche des Rameaux 2025\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010104-1024x499.jpg\" src=\"https:\/\/paroisse-notredame-sannedolon.fr\/mypress\/wp-content\/uploads\/2025\/04\/P1010104-1024x499.jpg\" alt=\"\" class=\"wp-image-10030\"\/><\/figure>\n\n\n\n<p class=\"has-medium-font-size\">Marie-Reine pour l\u2019\u00e9quipe de pr\u00e9paration, le 15 avril<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce samedi 12 avril 2025, \u00e0 Salaise-sur-Sanne, une trentaine d\u2019adultes des paroisses St Pierre et Notre Dame s\u2019\u00e9taient donn\u00e9s rendez-vous pour une marche autour de Salaise-sur-Sanne avec les jeunes de la cat\u00e9ch\u00e8se, de l\u2019aum\u00f4nerie, des \u00e9coles. Ce qui formait un groupe d\u2019une soixantaine de personnes toute g\u00e9n\u00e9ration confondue qui s\u2019est \u2026 <a class=\"continue-reading-link\" href=\"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/2025\/04\/15\/marche-des-rameaux-3\/\">Lire la suite <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-10021","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7rrt2-2BD","_links":{"self":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/10021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=10021"}],"version-history":[{"count":18,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/10021\/revisions"}],"predecessor-version":[{"id":10856,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/posts\/10021\/revisions\/10856"}],"wp:attachment":[{"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=10021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=10021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisse-notredame-sannedolon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=10021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}